{"id":425,"date":"2020-08-09T21:06:22","date_gmt":"2020-08-09T19:06:22","guid":{"rendered":"http:\/\/goodbyeworld.fr\/?p=425"},"modified":"2022-12-02T15:58:40","modified_gmt":"2022-12-02T14:58:40","slug":"pour-sauver-la-planete-donnons-du-chanvre-aux-poules","status":"publish","type":"post","link":"https:\/\/leafter.fr\/blog\/index.php\/2020\/08\/09\/pour-sauver-la-planete-donnons-du-chanvre-aux-poules\/","title":{"rendered":"CO2 : donnons du chanvre aux poules !"},"content":{"rendered":"\n<p>Selon <a href=\"https:\/\/www.sciencedirect.com\/science\/article\/abs\/pii\/S0959652618300751?via%3Dihub\">cette \u00e9tude espagnole<\/a>, l&#8217;empreinte carbone de <strong>12 \u0153ufs de poules \u00e9lev\u00e9es en batterie <\/strong>est en moyenne de<strong> 2.66 Kg eq\/CO2<\/strong>. L&#8217;alimentation des poules est en cause pour 63% (soit 1,67 Kg eq\/CO2). <\/p>\n\n\n\n<p>Sachant que <strong>la France a produit 14,3 milliards d\u2019\u0153ufs en 2018<\/strong> (Autant que \u00e7a ? &#8230; Oui la preuve <a href=\"https:\/\/oeuf-info.fr\/infos-filiere\/les-chiffres-cles\/\">ici<\/a> ). Environ <strong>50% sont des \u0153ufs en batterie<\/strong>, l&#8217;alimentation de ces poules serait responsable d&#8217;<strong>1 milliard de tonnes de CO2.<\/strong><\/p>\n\n\n\n<p>Ces poules sont principalement nourries de mati\u00e8res import\u00e9s : du ma\u00efs d&#8217;Ukraine ou de Roumanie et surtout des <strong>tourteaux de soja d&#8217;Am\u00e9rique du Sud<\/strong> m\u00e9lang\u00e9s \u00e0 de l&#8217;huile de palme.<\/p>\n\n\n\n<p>Dans le but de r\u00e9duire l&#8217;empreinte carbone, il y a un int\u00e9r\u00eat \u00e9vident \u00e0 <strong>remplacer tout ou partie de cette &#8220;junk food&#8221; par des grains locaux<\/strong>. Je pense en particulier aux  graines de chanvre. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Un meilleur bilan carbone<\/h2>\n\n\n\n<p>Imaginons que les exploitants d&#8217;\u00e9levages en batterie modifient leur mix habituel pour y apporter <strong>20% de graines de chanvre<\/strong>. Cette proportion ne modifie pas la productivit\u00e9. Il est n\u00e9cessaire tout comme pour nous de diversifier l&#8217;alimentation.<\/p>\n\n\n\n<p>Imagions que le chanvre soit cultiv\u00e9 localement pour sa paille<strong> <\/strong>et qu&#8217;on parvienne \u00e0 <strong>r\u00e9colter en un passage de machine la graine et la paille<\/strong>. On peut alors consid\u00e9rer que l&#8217;impact carbone de la culture, la r\u00e9colte et la distribution des graines aux \u00e9leveurs est n\u00e9gligeable. La culture du chanvre pour la fibre en vue de la production de b\u00e9ton de chanvre et d&#8217;isolant est une chaine qui a un bilan carbone n\u00e9gatif.<\/p>\n\n\n\n<p>En premi\u00e8re approximation, ce sc\u00e9nario permet donc <strong>une \u00e9conomie carbone de 20% de l&#8217;impact de l&#8217;alimentation des poules actuelle<\/strong>, soit <strong>200 millions de tonnes<\/strong> de CO2 par an. Si on rapporte \u00e0 la surface de chanvre cultiv\u00e9, on pourra observer un gain de 800Kg d&#8217;\u00e9quivalent CO2 par Hectare de chanvre ainsi utilis\u00e9.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Il n&#8217;y a pas que le carbone !<\/h2>\n\n\n\n<p>On peut \u00e9num\u00e9rer quelques co-b\u00e9n\u00e9fices \u00e0 cette m\u00e9thode : <\/p>\n\n\n\n<p>D&#8217;une part, nourrir les poules avec 20% de chanvre n&#8217;impacte pas la productivit\u00e9 et am\u00e9liore la qualit\u00e9 des \u0153ufs en <strong>augmentant le taux de &#8220;bon&#8221; cholest\u00e9rol<\/strong> (acides gras om\u00e9ga-3 et 6). <\/p>\n\n\n\n<p>Saviez-vous que les industriels ajoutent du colorant pour que les jaunes ne soient pas trop p\u00e2lichons ? Lorsque je compare la couleur &#8220;curcuma&#8221; des jaunes de mes propres poulettes \u00e0 ceux des \u0153ufs industriels, je parie un steak au soja que<strong> l&#8217;usage de colorant deviendrait inutile <\/strong>!<\/p>\n\n\n\n<p>D&#8217;autre part, en effet bonus, ce proc\u00e9d\u00e9 permet : <\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>d&#8217;<strong>\u00e9viter la d\u00e9forestation <\/strong>li\u00e9 \u00e0 la culture du soja et la production d&#8217;huile de palme,<\/li>\n\n\n\n<li>d&#8217;utiliser la paille dans d&#8217;autre fili\u00e8res comme la construction, le papier, l&#8217;\u00e9nergie<\/li>\n\n\n\n<li>d&#8217;am\u00e9liorer la bio-diversit\u00e9<\/li>\n\n\n\n<li>de favoriser un revenu d\u00e9cent pour les agriculteurs<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Le chanvre, \u00e7a coute un bras !<\/h2>\n\n\n\n<p>Le tarif pourrait constituer un certain frein. Analysons un peu.<\/p>\n\n\n\n<p>En premi\u00e8re approximation, le chenevis (la graine de chanvre) est vendu par l&#8217;agriculteur 450 \u20ac \/T. (source <a href=\"https:\/\/agriculture.gouv.fr\/telecharger\/88281?token=7809fea624ea2a6dc89c03165136bbfe\">plan fili\u00e8re chanvre<\/a>).<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/goodbyeworld.fr\/wp-content\/uploads\/2020\/08\/prix-du-tourteau-de-soja-1024x436.png\" alt=\"\" class=\"wp-image-426\"\/><figcaption class=\"wp-element-caption\">\u00c9volution du prix de la tonne de tourteau de soja<\/figcaption><\/figure>\n\n\n\n<p>La tonne de tourteau de soja \u00e9volue de 280 \u00e0 420\u20ac \/T. Disons qu&#8217;en moyenne elle est \u00e0 330\u20ac. Le co\u00fbt de cette \u00e9volution est donc en grosse maille de 40 Millions d&#8217;euros. C&#8217;est un peu plus d&#8217;1 centime par \u0153uf. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Quels sont les freins ?<\/h2>\n\n\n\n<p>Le premier probl\u00e8me est la <strong>concurrence  avec l&#8217;alimentation humaine<\/strong>. La tonne de grain de chanvre est mieux valoris\u00e9 dans ce circuit.<\/p>\n\n\n\n<p>Une poule en cage prend une ration quotidienne d&#8217;environ 150g et donc 30g de chanvre dans notre sc\u00e9nario \u00e0 20%. Cette m\u00eame poule produit 300 \u0153ufs par an en moyenne. Pour produire les 7 milliards d\u2019\u0153ufs en batterie, il faut 23 millions de poules et <strong>251 850 Tonnes de graines.<\/strong><\/p>\n\n\n\n<p>Il y a donc \u00e9galement un <strong>probl\u00e8me de volume n\u00e9cessaire<\/strong>. En 2016, la France a produit 9 088 tonnes de graine de chanvre. Il faudrait cultiver 250 000 Ha pour obtenir cette r\u00e9colte.<\/p>\n\n\n\n<p>Le chanvre a longtemps \u00e9t\u00e9 <strong>malmen\u00e9 par les lobbies<\/strong>. Son interdiction de culture aux \u00e9tats-unis a favoris\u00e9 les industries fossiles. Rappelons que l&#8217;huile de chanvre permet de fabriquer du bio\u00e9thanol qui concurrence le p\u00e9trole. On peut directement l&#8217;utiliser dans les v\u00e9hicules agricoles. Il peut aussi se m\u00e9langer au gasoil sans aucune modification du moteur.<\/p>\n\n\n\n<p><strong>L&#8217;\u00e9quipement agricole n&#8217;est pas disponible<\/strong>. Aucune machine ne permet, sans modification, de r\u00e9colter \u00e0 la fois la paille et la graine. Il faut adapter une ensileuse pour pouvoir travailler correctement. <\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" src=\"https:\/\/goodbyeworld.fr\/wp-content\/uploads\/2020\/08\/14358-article-chanvre.jpg\" alt=\"\" class=\"wp-image-437\"\/><figcaption class=\"wp-element-caption\">Moissonneuse batteuse John Deere 9680WTS modifi\u00e9e pour r\u00e9colter la paille et les graines simultan\u00e9ment (cr\u00e9dits <a href=\"http:\/\/www.horizons-journal.fr\/article\/le-chanvre-peut-desormais-se-recolter-en-une-seule-passe,884.php\">http:\/\/www.horizons-journal.fr<\/a>)<\/figcaption><\/figure>\n<\/div>\n\n\n<p>Les usines de d\u00e9fibrages semblent \u00e9galement souffrir d&#8217;un <strong>proc\u00e9d\u00e9 contraignant et peu maitris\u00e9<\/strong>. Il y a aussi la sous-exploitation des unit\u00e9s de production par <strong>manque de mati\u00e8re premi\u00e8re<\/strong>. Ces deux probl\u00e8mes sont \u00e0 l&#8217;origine des  <strong>faillites<\/strong> de Gatichanvre dans l&#8217;Essonne, de Hemp.be et des chanvriers de l&#8217;Est. <\/p>\n\n\n\n<p>Il y a une contrainte sur la<strong> localisation des champs qui doivent \u00eatre \u00e0 proximit\u00e9 des transformateurs<\/strong>. La paille ne peut pas voyager sur de longues distances.  A tel point que les agriculteurs situ\u00e9s trop loin ne trouvent pas de d\u00e9bouch\u00e9s : ils laissent la paille sur le champ.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Comment s&#8217;en sortir ?<\/h2>\n\n\n\n<p>Sans tout r\u00e9volutionner du jour au lendemain, il faut clairement <strong>encourager le d\u00e9veloppement<\/strong> de cette fili\u00e8re prometteuse.<\/p>\n\n\n\n<p>En 2019, les cultures de chanvre \u00e9taient subventionn\u00e9es par l&#8217;Union Europ\u00e9enne \u00e0 hauteur de 112\u20ac par hectare. <strong>Augmenter cette aide <\/strong>est un d\u00e9but de r\u00e9ponse. Pour que les agriculteurs choisissent cette culture, il faut qu&#8217;elle soit rentable. Rappelons que sur le plan \u00e9cologique, le chanvre a de nombreux atouts : <strong>il ne n\u00e9cessite pas de pesticide, peu d&#8217;engrais et peu d&#8217;eau<\/strong>. C&#8217;est aussi une bonne culture en rotation. J&#8217;en parle dans cet <a href=\"https:\/\/goodbyeworld.fr\/index.php\/2020\/04\/08\/le-chanvre-un-tresor-de-guerre-pour-la-planete\/\">autre article<\/a>.<\/p>\n\n\n\n<p>La <strong>valorisation du CO2 capt\u00e9<\/strong> lors de la photosynth\u00e8se par la plante est un autre levier. Le gouvernement encourage les projets bas carbone mais <strong>il n&#8217;existe pas \u00e0 ce jour de m\u00e9thode de captation de CO2 li\u00e9e \u00e0 la culture du chanvre<\/strong>. Cela repr\u00e9sente un co\u00fbt initial d&#8217;environ 150k\u20ac qu&#8217;il n&#8217;est pas \u00e9vident de mettre sur la table. Comme l&#8217;indique ce graphique, la captation du CO2 par le chanvre est 7 fois plus efficace que replanter des arbres.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" src=\"https:\/\/goodbyeworld.fr\/wp-content\/uploads\/2020\/08\/chanvreforet.png\" alt=\"\" class=\"wp-image-430\"\/><\/figure>\n<\/div>\n\n\n<p>Enfin, nous pouvons imaginer des <strong>solutions de transports innovantes et bas carbone<\/strong>. Il faut permettre le transport des pailles sur des distances plus importantes avec un bilan carbone acceptable. On peut penser au transport \u00e0 l&#8217;hydrog\u00e8ne issu de la biomasse. L&#8217;initiative de <a href=\"https:\/\/qairos-energies.com\/\">Qairos Energie<\/a> qui construit une usine pilote dans la Sarthe est un bel exemple. Vous noterez au passage que la biomasse utilis\u00e9e est &#8230; du chanvre ? Oh ! Encore un nouveau d\u00e9bouch\u00e9 \ud83d\ude42<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Conclusion<\/h2>\n\n\n\n<p>Je suis personnellement impliqu\u00e9 dans la r\u00e9solution de cette \u00e9quation plut\u00f4t complexe au travers Leafter <\/p>\n\n\n\n<p>Une r\u00e9volution passe par des actes et il y a urgence absolue !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Analyse d&#8217;une m\u00e9thode de r\u00e9duction de CO2 consistant \u00e0 donner des graines de chanvre aux poules en cage \u00e0 la place de leur Junk Food au soja.<\/p>\n","protected":false},"author":1,"featured_media":930,"comment_status":"open","ping_status":"open","sticky":true,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[27,28,20,21,29,30,31,32,33,34],"class_list":["post-425","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classe","tag-bilan-carbone","tag-carbone","tag-chanvre","tag-co2","tag-hydrogene","tag-jancovici","tag-oeuf","tag-palme","tag-poule","tag-soja"],"_links":{"self":[{"href":"https:\/\/leafter.fr\/blog\/index.php\/wp-json\/wp\/v2\/posts\/425","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/leafter.fr\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/leafter.fr\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/leafter.fr\/blog\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/leafter.fr\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=425"}],"version-history":[{"count":2,"href":"https:\/\/leafter.fr\/blog\/index.php\/wp-json\/wp\/v2\/posts\/425\/revisions"}],"predecessor-version":[{"id":931,"href":"https:\/\/leafter.fr\/blog\/index.php\/wp-json\/wp\/v2\/posts\/425\/revisions\/931"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/leafter.fr\/blog\/index.php\/wp-json\/wp\/v2\/media\/930"}],"wp:attachment":[{"href":"https:\/\/leafter.fr\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=425"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/leafter.fr\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=425"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/leafter.fr\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=425"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}